{"id":9192,"date":"2023-01-19T12:41:50","date_gmt":"2023-01-19T11:41:50","guid":{"rendered":"https:\/\/www.martinennalsaward.org\/?p=9192"},"modified":"2023-01-20T09:41:47","modified_gmt":"2023-01-20T08:41:47","slug":"tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023","status":"publish","type":"post","link":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/","title":{"rendered":"Trois figures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Venezuela, au Tchad,  et au Cachemire, recevront le Prix Martin Ennals 2023"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-9199 size-full\" src=\"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1.jpg 1920w, https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1-300x169.jpg 300w, https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1-1024x576.jpg 1024w, https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1-768x432.jpg 768w, https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1-1536x864.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><b><span data-contrast=\"auto\">Gen\u00e8ve, le 19\u202fjanvier\u202f2023\u202f<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><i><span data-contrast=\"auto\">Trois\u202ffigures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Tchad, au Venezuela et au Cachemire, recevront le Prix Martin Ennals\u202f2023 le 16\u202ff\u00e9vrier\u202f2023 \u00e0 Gen\u00e8ve, en Suisse.<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Un jury compos\u00e9 de\u202fdix des plus importantes ONG de d\u00e9fense des droits humains dans le monde &#8211; <\/span><i><span data-contrast=\"auto\">Amnistie Internationale, Human Rights Watch, la F\u00e9d\u00e9ration internationale des droits de l&rsquo;homme, Huridocs, Pain pour le monde, Human Rights First, l&rsquo;Organisation mondiale contre la torture, la Commission internationale de juristes (CIJ), le Service international pour les droits de l&rsquo;homme (SIDH) et Front Line Defenders<\/span><\/i><span data-contrast=\"auto\"> &#8211; a s\u00e9lectionn\u00e9, apr\u00e8s une longue p\u00e9riode de d\u00e9lib\u00e9ration, les trois\u202fd\u00e9fenseur-euse-s des droits humains qui, selon lui, m\u00e9ritent d&rsquo;\u00eatre reconnu-e-s et honor\u00e9-e-s par le Prix de\u202f2023.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h4><i><span data-contrast=\"auto\">Delphine Djiraib\u00e9<\/span><\/i><span data-contrast=\"auto\"> (Tchad), <\/span><i><span data-contrast=\"auto\">Feliciano Reyna<\/span><\/i><span data-contrast=\"auto\"> (Venezuela) et <\/span><i><span data-contrast=\"auto\">Khurram Parvez<\/span><\/i><span data-contrast=\"auto\"> (Cachemire), les laur\u00e9at-e-s de\u202f2023, partagent le m\u00eame courage, la m\u00eame passion et la m\u00eame d\u00e9termination pour faire entendre la voix des sans-voix sur la sc\u00e8ne internationale, en d\u00e9pit des d\u00e9fis permanents qu&rsquo;ils doivent relever, parfois au risque de leur vie.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h4>\n<p><i><span data-contrast=\"auto\">\u00ab\u202fNous sommes particuli\u00e8rement fiers d&rsquo;honorer ces trois\u202flaur\u00e9at-e-s exceptionnel-le-s qui ont consacr\u00e9 plus de 30\u202fans de leur vie \u00e0 cr\u00e9er des mouvements qui rendent justice aux victimes ou fournissent des m\u00e9dicaments aux populations marginalis\u00e9es. Ils ont fait des droits humains une r\u00e9alit\u00e9 pour des milliers de personnes dans leur pays.\u202f\u00bb\u00a0\u00a0<\/span><\/i><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p style=\"text-align: right;\"><span data-contrast=\"auto\">&#8211; Hans Thoolen, Pr\u00e9sident du Jury du Prix Martin Ennals \u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:3,&quot;335551620&quot;:3,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Les trois\u202flaur\u00e9at-e-s du Prix Martin Ennals\u202f2023\u202f:<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">L&rsquo;une des premi\u00e8res avocates du Tchad, <\/span><b><span data-contrast=\"auto\">Delphine Kemneloum Djiraib\u00e9 <\/span><\/b><span data-contrast=\"auto\">est une pionni\u00e8re du mouvement des droits humains dans l&rsquo;un des pays les plus pauvres du monde, gangren\u00e9 par la corruption et les violations des droits humains. Convaincue que son r\u00f4le est de \u00ab\u202f<\/span><i><span data-contrast=\"auto\">d\u00e9fier le pouvoir<\/span><\/i><span data-contrast=\"auto\">\u202f\u00bb, Delphine d\u00e9fend depuis plus de\u202f30 ans la cause des victimes et le processus d\u00e9mocratique. Elle a jou\u00e9 un r\u00f4le cl\u00e9 dans la traduction en justice de l&rsquo;ancien dictateur Hiss\u00e8ne Habr\u00e9. Me\u202fDjiraib\u00e9 dirige l&rsquo;organisation non gouvernementale Public Interest Law Center (PILC), laquelle forme des b\u00e9n\u00e9voles et accompagne les citoyen-ne-s qui cherchent \u00e0 obtenir justice pour les violations de leurs droits. Ces derni\u00e8res ann\u00e9es, elle a \u00e9t\u00e9 particuli\u00e8rement active dans la lutte contre les violences sexistes et elle est en train de cr\u00e9er le premier centre de soutien psychologique pour les femmes au Tchad, qui comprendra un abri d&rsquo;urgence pour les femmes victimes de violences domestiques.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Feliciano Reyna\u202f: <\/span><\/b><span data-contrast=\"auto\">Apr\u00e8s la mort de son partenaire Rafael, d\u00e9c\u00e9d\u00e9 en\u202f1995 \u00e0 cause du sida, Feliciano Reyna, alors architecte, a fond\u00e9 Acci\u00f3n Solidaria pour fournir des m\u00e9dicaments et des traitements indispensables aux V\u00e9n\u00e9zu\u00e9liens vivant avec le VIH et le sida. Feliciano et Acci\u00f3n Solidaria ont commenc\u00e9 \u00e0 d\u00e9fendre l&rsquo;acc\u00e8s \u00e0 la sant\u00e9 pour les LGBTQI, une population marginalis\u00e9e dans un pays o\u00f9 les services de sant\u00e9 \u00e9taient en d\u00e9clin et la corruption en hausse. Ils ont cr\u00e9\u00e9 la premi\u00e8re ligne d&rsquo;assistance nationale sur le sida au Venezuela et ont men\u00e9 une campagne nationale de sensibilisation, qui a \u00e9t\u00e9 diffus\u00e9e \u00e0 la t\u00e9l\u00e9vision et dans les cin\u00e9mas, et qui a b\u00e9n\u00e9fici\u00e9 d&rsquo;une couverture \u00e0 la radio et dans les magazines. Feliciano Reyna a ensuite fond\u00e9 CODEVIDA, une coalition d&rsquo;organisations v\u00e9n\u00e9zu\u00e9liennes qui d\u00e9fendent les droits des citoyens \u00e0 la sant\u00e9 et \u00e0 la vie. Il explique\u202f: \u00ab\u202f<\/span><i><span data-contrast=\"auto\">Nous avons \u00e9t\u00e9 directement plong\u00e9s dans toute la complexit\u00e9 de la crise humanitaire du Venezuela<\/span><\/i><span data-contrast=\"auto\">\u202f\u00bb. Malgr\u00e9 les menaces permanentes, il travaille, depuis\u202f2006, en \u00e9troite collaboration avec les m\u00e9canismes de l&rsquo;ONU pour d\u00e9fendre les droits humains dans son pays. En\u202f2019, son effort de plaidoyer a contribu\u00e9 \u00e0 la cr\u00e9ation de la Mission internationale ind\u00e9pendante d&rsquo;\u00e9tablissement des faits sur le Venezuela.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Khurram Parvez\u202f: <\/span><\/b><span data-contrast=\"auto\">C&rsquo;est \u00e0 l&rsquo;\u00e2ge de treize\u202fans, lorsqu\u2019il est t\u00e9moin de l&rsquo;assassinat de son grand-p\u00e8re lors d&rsquo;une manifestation organis\u00e9e pour protester contre les mauvais traitements inflig\u00e9s aux femmes devant sa maison au Cachemire, que Khurram Parvez fait le choix de \u00ab\u202f<\/span><i><span data-contrast=\"auto\">ne pas prendre part \u00e0 des actes d\u2019incitation \u00e0 la violence et de vengeance<\/span><\/i><span data-contrast=\"auto\">\u202f\u00bb, mais plut\u00f4t de devenir un \u00ab\u202f<\/span><i><span data-contrast=\"auto\">militant non violent<\/span><\/i><span data-contrast=\"auto\">\u202f\u00bb. Il a fond\u00e9 la Coalition de la soci\u00e9t\u00e9 civile de l\u2019\u00c9tat de Jammu-et-Cachemire (JKCCS) et pr\u00e9side la F\u00e9d\u00e9ration asiatique contre les disparitions involontaires. Pendant quinze\u202fans, il a voyag\u00e9 dans les zones les plus recul\u00e9es de la r\u00e9gion pour parler aux victimes d&rsquo;abus, recueillir des informations, documenter et rapporter leurs histoires. Sous sa direction, la JKCCS s&rsquo;est montr\u00e9e tr\u00e8s efficace pour traduire dans la r\u00e9alit\u00e9 locale les protections garanties par le droit international des droits humains. Malgr\u00e9 les attaques continues du gouvernement indien contre son droit \u00e0 la libert\u00e9 d&rsquo;expression, son emprisonnement en\u202f2016 et la perte d&rsquo;une jambe en raison d\u2019une blessure caus\u00e9e par une mine antipersonnel, Khurram continue inlassablement de faire entendre la v\u00e9rit\u00e9 et repr\u00e9sente une source d&rsquo;inspiration pour la soci\u00e9t\u00e9 civile et la population locale. En novembre\u202f2021, il a \u00e9t\u00e9 arr\u00eat\u00e9 en vertu de la Loi relative \u00e0 la pr\u00e9vention des activit\u00e9s ill\u00e9gales (UAPA) sur la base d\u2019accusations motiv\u00e9es par des consid\u00e9rations politiques. Il est encore d\u00e9tenu sans proc\u00e8s en Inde.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Le Prix Martin Ennals\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Cr\u00e9\u00e9 en\u202f1992, le Prix Martin Ennals (PME) est un prix annuel qui apporte reconnaissance, soutien et protection \u00e0 des d\u00e9fenseur-euse-s des droits humains du monde entier. Le Prix donne une visibilit\u00e9 aux laur\u00e9at-e-s et met en lumi\u00e8re la situation des droits humains dans leur pays.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">La c\u00e9r\u00e9monie du PME, organis\u00e9e conjointement avec la Ville de Gen\u00e8ve, aura lieu le 16\u202ff\u00e9vrier\u202f2023 \u00e0 la salle communale de Plainpalais. Diffus\u00e9e en direct, la c\u00e9r\u00e9monie attire d\u2019un large publique local et international des supporters des droits humains, venus participer \u00e0 un \u00e9v\u00e9nement inspirant qui c\u00e9l\u00e8bre les accomplissements et l&rsquo;engagement des activistes exceptionnels.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<h4><i><span data-contrast=\"auto\">\u00ab<\/span><\/i><i><span data-contrast=\"auto\">Ville internationale, multiculturelle, si\u00e8ge de nombreuses organisations gouvernementales et non gouvernementales, Gen\u00e8ve a plac\u00e9, depuis de nombreuses ann\u00e9es, la d\u00e9fense des droits humains comme une des valeurs cardinales de son action politique. Le Prix Martin Ennals fait partie des \u00e9v\u00e9nements qu&rsquo;elle soutient afin de sensibiliser le public genevois aux droits fondamentaux et \u00e0 l&rsquo;importance de les d\u00e9fendre, particuli\u00e8rement en ces temps troubl\u00e9<\/span><\/i><span data-contrast=\"auto\">s\u202f\u00bb, conclut <\/span><b><span data-contrast=\"auto\">Alfonso Gomez, Vice-Pr\u00e9sident de la Ville de Gen\u00e8ve.<\/span><\/b><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/h4>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\">Pour plus d\u2019informations, veuillez contacter\u202f:\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Vivian Hakkak\u00a0<\/span><b><span data-contrast=\"none\">\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:147,&quot;335559738&quot;:318,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"none\">Responsable de la communication<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:147,&quot;335559738&quot;:39,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><a href=\"mailto:communications@martinennals.ch\">communications@martinennals.ch<\/a><\/p>\n<p><span data-contrast=\"none\">T\u00e9l\u00e9phone mobile\u202f: +41.78.740 24 22<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:156,&quot;335559738&quot;:39,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Gen\u00e8ve, le 19\u202fjanvier\u202f2023\u202f\u00a0 Trois\u202ffigures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Tchad, au Venezuela et au Cachemire, recevront le Prix Martin Ennals\u202f2023 le 16\u202ff\u00e9vrier\u202f2023 \u00e0 Gen\u00e8ve, en Suisse.\u00a0 Un jury compos\u00e9 de\u202fdix des plus importantes ONG de d\u00e9fense des droits humains dans le monde &#8211; Amnistie Internationale, Human Rights Watch, la F\u00e9d\u00e9ration<a class=\"read-more\" href=\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":9,"featured_media":9199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[237,227,624,2],"tags":[627,628],"news_section":[343,549],"class_list":["post-9192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-laureat","category-news-fr-2","category-non-classifiee","tag-emadeddin-baghi","tag-iran-fr-2","news_section-news","news_section-news-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trois figures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Venezuela, au Tchad, et au Cachemire, recevront le Prix Martin Ennals 2023 - Martin Ennals Award<\/title>\n<meta name=\"description\" content=\"En l&#039;honneur de Aktham Naisse, le cin\u00e9aste Willem Offenberg se souvient d&#039;une interview qu&#039;il a r\u00e9alis\u00e9e avec lui \u00e0 Damas en 2005.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un th\u00e9 \u00e0 Damas avec un g\u00e9ant des droits humains\" \/>\n<meta property=\"og:description\" content=\"En l&#039;honneur de ce g\u00e9ant des droits humains parti beaucoup trop t\u00f4t, le cin\u00e9aste Willem Offenberg se souvient d&#039;une interview qu&#039;il a r\u00e9alis\u00e9e avec Aktham Naisse \u00e0 Damas en 2005.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Martin Ennals Award\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T11:41:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-20T08:41:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2022\/02\/aktham-naisse-02-5-300x300-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Media MEA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Un th\u00e9 \u00e0 Damas avec un g\u00e9ant des droits humains\" \/>\n<meta name=\"twitter:description\" content=\"En l&#039;honneur de ce g\u00e9ant des droits humains parti beaucoup trop t\u00f4t, le cin\u00e9aste Willem Offenberg se souvient d&#039;une interview qu&#039;il a r\u00e9alis\u00e9e avec Aktham Naisse \u00e0 Damas en 2005.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2022\/02\/aktham-naisse-02-5-300x300-1.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Media MEA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/\",\"url\":\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/\",\"name\":\"Trois figures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Venezuela, au Tchad, et au Cachemire, recevront le Prix Martin Ennals 2023 - Martin Ennals Award\",\"isPartOf\":{\"@id\":\"https:\/\/www.martinennalsaward.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1.jpg\",\"datePublished\":\"2023-01-19T11:41:50+00:00\",\"dateModified\":\"2023-01-20T08:41:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.martinennalsaward.org\/#\/schema\/person\/e5b5e129cdd55c19f6492f506c7aae2b\"},\"description\":\"En l'honneur de Aktham Naisse, le cin\u00e9aste Willem Offenberg se souvient d'une interview qu'il a r\u00e9alis\u00e9e avec lui \u00e0 Damas en 2005.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#primaryimage\",\"url\":\"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1.jpg\",\"contentUrl\":\"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.martinennalsaward.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trois figures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Venezuela, au Tchad, et au Cachemire, recevront le Prix Martin Ennals 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.martinennalsaward.org\/#website\",\"url\":\"https:\/\/www.martinennalsaward.org\/\",\"name\":\"Martin Ennals Award\",\"description\":\"For Human Rights Defenders\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.martinennalsaward.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.martinennalsaward.org\/#\/schema\/person\/e5b5e129cdd55c19f6492f506c7aae2b\",\"name\":\"Media MEA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.martinennalsaward.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dddd036b53ffcc641447ce50b0f8dd31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dddd036b53ffcc641447ce50b0f8dd31?s=96&d=mm&r=g\",\"caption\":\"Media MEA\"},\"sameAs\":[\"http:\/\/www.martinennalsaward.org\",\"media@martinennalsaward.org\"],\"url\":\"https:\/\/www.martinennalsaward.org\/fr\/author\/mea-media\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trois figures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Venezuela, au Tchad, et au Cachemire, recevront le Prix Martin Ennals 2023 - Martin Ennals Award","description":"En l'honneur de Aktham Naisse, le cin\u00e9aste Willem Offenberg se souvient d'une interview qu'il a r\u00e9alis\u00e9e avec lui \u00e0 Damas en 2005.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Un th\u00e9 \u00e0 Damas avec un g\u00e9ant des droits humains","og_description":"En l'honneur de ce g\u00e9ant des droits humains parti beaucoup trop t\u00f4t, le cin\u00e9aste Willem Offenberg se souvient d'une interview qu'il a r\u00e9alis\u00e9e avec Aktham Naisse \u00e0 Damas en 2005.","og_url":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/","og_site_name":"Martin Ennals Award","article_published_time":"2023-01-19T11:41:50+00:00","article_modified_time":"2023-01-20T08:41:47+00:00","og_image":[{"width":300,"height":300,"url":"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2022\/02\/aktham-naisse-02-5-300x300-1.png","type":"image\/png"}],"author":"Media MEA","twitter_card":"summary_large_image","twitter_title":"Un th\u00e9 \u00e0 Damas avec un g\u00e9ant des droits humains","twitter_description":"En l'honneur de ce g\u00e9ant des droits humains parti beaucoup trop t\u00f4t, le cin\u00e9aste Willem Offenberg se souvient d'une interview qu'il a r\u00e9alis\u00e9e avec Aktham Naisse \u00e0 Damas en 2005.","twitter_image":"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2022\/02\/aktham-naisse-02-5-300x300-1.png","twitter_misc":{"\u00c9crit par":"Media MEA","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/","url":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/","name":"Trois figures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Venezuela, au Tchad, et au Cachemire, recevront le Prix Martin Ennals 2023 - Martin Ennals Award","isPartOf":{"@id":"https:\/\/www.martinennalsaward.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1.jpg","datePublished":"2023-01-19T11:41:50+00:00","dateModified":"2023-01-20T08:41:47+00:00","author":{"@id":"https:\/\/www.martinennalsaward.org\/#\/schema\/person\/e5b5e129cdd55c19f6492f506c7aae2b"},"description":"En l'honneur de Aktham Naisse, le cin\u00e9aste Willem Offenberg se souvient d'une interview qu'il a r\u00e9alis\u00e9e avec lui \u00e0 Damas en 2005.","breadcrumb":{"@id":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#primaryimage","url":"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1.jpg","contentUrl":"https:\/\/www.martinennalsaward.org\/wp-content\/uploads\/2023\/01\/three-laureates-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.martinennalsaward.org\/fr\/tchad-au-venezuela-et-au-cachemire-recevront-le-prix-martin-ennals-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.martinennalsaward.org\/"},{"@type":"ListItem","position":2,"name":"Trois figures exceptionnelles et pionni\u00e8res du mouvement des droits humains au Venezuela, au Tchad, et au Cachemire, recevront le Prix Martin Ennals 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.martinennalsaward.org\/#website","url":"https:\/\/www.martinennalsaward.org\/","name":"Martin Ennals Award","description":"For Human Rights Defenders","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.martinennalsaward.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.martinennalsaward.org\/#\/schema\/person\/e5b5e129cdd55c19f6492f506c7aae2b","name":"Media MEA","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.martinennalsaward.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dddd036b53ffcc641447ce50b0f8dd31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dddd036b53ffcc641447ce50b0f8dd31?s=96&d=mm&r=g","caption":"Media MEA"},"sameAs":["http:\/\/www.martinennalsaward.org","media@martinennalsaward.org"],"url":"https:\/\/www.martinennalsaward.org\/fr\/author\/mea-media\/"}]}},"_links":{"self":[{"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/posts\/9192"}],"collection":[{"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/comments?post=9192"}],"version-history":[{"count":0,"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/posts\/9192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/media\/9199"}],"wp:attachment":[{"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/media?parent=9192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/categories?post=9192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/tags?post=9192"},{"taxonomy":"news_section","embeddable":true,"href":"https:\/\/www.martinennalsaward.org\/fr\/wp-json\/wp\/v2\/news_section?post=9192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}